{"id":1579,"date":"2026-09-01T16:40:10","date_gmt":"2026-09-01T16:40:10","guid":{"rendered":"https:\/\/innova343.net\/?p=1579"},"modified":"2026-09-01T16:40:10","modified_gmt":"2026-09-01T16:40:10","slug":"el-sentido-comun","status":"publish","type":"post","link":"https:\/\/innova343.net\/index.php\/2026\/09\/01\/el-sentido-comun\/","title":{"rendered":"El sentido com\u00fan"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Durante a\u00f1os hemos asistido a una carrera por digitalizar las aulas. Ordenadores, tabletas, plataformas y libros digitales fueron entrando en los centros educativos casi como sin\u00f3nimo inevitable de innovaci\u00f3n. Ahora, cuando algunas escuelas empiezan a recuperar los libros de papel, la escritura a mano y un uso m\u00e1s limitado de las pantallas, quiz\u00e1 no estemos ante un paso atr\u00e1s, sino ante algo mucho m\u00e1s sencillo: la recuperaci\u00f3n del sentido com\u00fan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La tecnolog\u00eda ha aportado enormes posibilidades a la educaci\u00f3n y ser\u00eda absurdo renunciar a ellas. Un ordenador puede abrir una ventana extraordinaria al conocimiento, una plataforma puede facilitar aprendizajes que antes eran dif\u00edciles de imaginar y la inteligencia artificial puede convertirse en una poderosa aliada para docentes y alumnos. El problema nunca ha sido la tecnolog\u00eda, sino confundir su presencia con la innovaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por eso, quiz\u00e1 el debate no deber\u00eda plantearse en t\u00e9rminos de papel contra pantalla, ni tampoco de inteligencia humana contra inteligencia artificial. La pregunta verdaderamente educativa es otra: \u00bfqu\u00e9 recurso ayuda mejor al alumno a aprender en cada momento?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La llegada de la inteligencia artificial hace todav\u00eda m\u00e1s necesaria esta reflexi\u00f3n. No debemos temerla ni demonizarla. Al contrario, debemos ense\u00f1ar a utilizarla de forma cr\u00edtica, \u00e9tica y creativa, aprovechando su enorme potencial para personalizar el aprendizaje, generar nuevas oportunidades y ayudar a comprender mejor el mundo. Pero tambi\u00e9n debemos preservar aquellos momentos en los que leer despacio, escribir, dialogar, equivocarse, concentrarse o resolver un problema sin ayuda resultan esenciales para aprender.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Educar no consiste en elegir entre tecnolog\u00eda y tradici\u00f3n, sino en saber combinar ambas con inteligencia. Y quiz\u00e1, en una sociedad saturada de pantallas, est\u00edmulos y respuestas inmediatas, una de las funciones m\u00e1s importantes de la escuela sea convertirse en un <strong>refugio cognitivo<\/strong>: un espacio donde la tecnolog\u00eda, incluida la inteligencia artificial, est\u00e9 al servicio del pensamiento humano y nunca al rev\u00e9s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante a\u00f1os hemos asistido a una carrera por digitalizar las aulas. Ordenadores, tabletas, plataformas y libros digitales fueron entrando en los centros educativos casi como sin\u00f3nimo inevitable de innovaci\u00f3n. Ahora, cuando algunas escuelas empiezan a recuperar los libros de papel, la escritura a mano y un uso m\u00e1s limitado de las pantallas, quiz\u00e1 no estemos<\/p>\n<p class=\"more-link\"><a href=\"https:\/\/innova343.net\/index.php\/2026\/09\/01\/el-sentido-comun\/\" class=\"themebutton\">Read More<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1579","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/innova343.net\/index.php\/wp-json\/wp\/v2\/posts\/1579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/innova343.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/innova343.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/innova343.net\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/innova343.net\/index.php\/wp-json\/wp\/v2\/comments?post=1579"}],"version-history":[{"count":1,"href":"https:\/\/innova343.net\/index.php\/wp-json\/wp\/v2\/posts\/1579\/revisions"}],"predecessor-version":[{"id":1580,"href":"https:\/\/innova343.net\/index.php\/wp-json\/wp\/v2\/posts\/1579\/revisions\/1580"}],"wp:attachment":[{"href":"https:\/\/innova343.net\/index.php\/wp-json\/wp\/v2\/media?parent=1579"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/innova343.net\/index.php\/wp-json\/wp\/v2\/categories?post=1579"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/innova343.net\/index.php\/wp-json\/wp\/v2\/tags?post=1579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}